{"id":47,"count":14,"description":"","link":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/","name":"Blog","slug":"blog-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blog archivos - Cata de Vinos Barcelona<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Cata de Vinos Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/category\\\/blog-en\\\/\",\"url\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/category\\\/blog-en\\\/\",\"name\":\"Blog archivos - Cata de Vinos Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/category\\\/blog-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/category\\\/blog-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/\",\"name\":\"Cata de Vinos Barcelona\",\"description\":\"La Mejor Cata de Vinos de Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#organization\",\"name\":\"Cata de Vinos Barcelona\",\"url\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cata-de-Vinos-B-1.png\",\"contentUrl\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cata-de-Vinos-B-1.png\",\"width\":500,\"height\":202,\"caption\":\"Cata de Vinos Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cata-de-vinos.barcelona\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blog archivos - Cata de Vinos Barcelona","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Blog archivos","og_url":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/","og_site_name":"Cata de Vinos Barcelona","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/","url":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/","name":"Blog archivos - Cata de Vinos Barcelona","isPartOf":{"@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/category\/blog-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cata-de-vinos.barcelona\/en\/"},{"@type":"ListItem","position":2,"name":"Blog"}]},{"@type":"WebSite","@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#website","url":"https:\/\/www.cata-de-vinos.barcelona\/en\/","name":"Cata de Vinos Barcelona","description":"La Mejor Cata de Vinos de Barcelona","publisher":{"@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cata-de-vinos.barcelona\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#organization","name":"Cata de Vinos Barcelona","url":"https:\/\/www.cata-de-vinos.barcelona\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.cata-de-vinos.barcelona\/wp-content\/uploads\/2024\/07\/Cata-de-Vinos-B-1.png","contentUrl":"https:\/\/www.cata-de-vinos.barcelona\/wp-content\/uploads\/2024\/07\/Cata-de-Vinos-B-1.png","width":500,"height":202,"caption":"Cata de Vinos Barcelona"},"image":{"@id":"https:\/\/www.cata-de-vinos.barcelona\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cata-de-vinos.barcelona\/en\/wp-json\/wp\/v2\/categories\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cata-de-vinos.barcelona\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.cata-de-vinos.barcelona\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.cata-de-vinos.barcelona\/en\/wp-json\/wp\/v2\/posts?categories=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}